{"id":1477,"date":"2022-01-30T13:03:05","date_gmt":"2022-01-30T19:03:05","guid":{"rendered":"https:\/\/ando.mx\/enterate\/?p=1477"},"modified":"2022-11-29T12:19:54","modified_gmt":"2022-11-29T18:19:54","slug":"email-marketing","status":"publish","type":"post","link":"http:\/\/ando.mx\/enterate\/email-marketing\/","title":{"rendered":"Email Marketing"},"content":{"rendered":"<p>El correo electr\u00f3nico se ha vuelto una herramienta fundamental y una pieza clave para poder utilizar diversas aplicaciones, hacer compras por internet, crear cuentas en redes sociales, requisito para tr\u00e1mites personales, etc.<\/p>\n<p>Qui\u00e9n pensar\u00eda que una simple cuenta de correo electr\u00f3nico pasar\u00eda de solo enviar y recibir correos para comunicar algo, a ser parte indispensable del registro para poder utilizar la mayor\u00eda de las herramientas que utilizamos en la actualidad.<\/p>\n<p>Principalmente vemos que las cuentas de correo que se utilizan para trabajo, tienden a ser monitoreadas y revisadas todo el tiempo de jornada laboral, por lo que, puede ser m\u00e1s eficaz transmitir un mensaje, ya que de forma inconsciente se tiene que abrir para revisar su contenido.<\/p>\n<p>Derivado de lo anterior podemos decir que el E-mail Marketing es un arma, que s\u00ed se utiliza correctamente, puede potencializar tu negocio y la interacci\u00f3n con las personas, ya sea clientes actuales o prospectos que busquen informaci\u00f3n sobre lo que ofrecemos.<\/p>\n<p>Los formatos de comunicaci\u00f3n para esta herramienta son diversos, te platicamos un poco para que conozcas las diferencias y para qu\u00e9 sirve cada uno.<\/p>\n<h2><strong>Newsletter<\/strong><\/h2>\n<p>Con este podr\u00e1s tener una comunicaci\u00f3n que nutrir\u00e1 la relaci\u00f3n con tus leads y clientes de forma sencilla. Pueden abordar diversos intereses dentro de un tema amplio, ya sea, promover un producto para los que a\u00fan no se deciden a comprar o algo relevante para los que ya conocen lo que ofrecemos.<\/p>\n<h3><strong>Email promocional<\/strong><\/h3>\n<p>En este nos referimos a la promoci\u00f3n de una oferta, es dar a conocer a los clientes si tenemos promociones en alg\u00fan producto, se\u00f1alar las caracter\u00edsticas de este y destacar sus diferencias ante la competencia. Podemos optimizar este formato con la segmentaci\u00f3n de la audiencia que est\u00e1 interesada en alg\u00fan producto espec\u00edfico.<\/p>\n<h3><strong>Email estacional<\/strong><\/h3>\n<p>Como se menciona en el t\u00edtulo es solo estacional, es decir, en fechas especiales. Principalmente se centran en los cumplea\u00f1os, fechas conmemorativas y celebraciones en general, con este formato podemos hacer que los leads se sientan importantes al formar parte de nuestra comunidad como clientes o futuros clientes.<\/p>\n<h3><strong>Email Marketing de bienvenida<\/strong><\/h3>\n<p>Este email lo enviar\u00e1s a tu prospecto tan pronto como se convierta en Lead. Puede no parecer importante, pero su funci\u00f3n principal es avanzar al usuario en Su proceso de compra, es decir, proporcionar informaci\u00f3n relevante.<\/p>\n<h3><strong>Email para eCommerce<\/strong><\/h3>\n<p>Este formato te ayudar\u00e1 a enviar promociones divulgar novedades o disminuir la tasa de carritos abandonados. Podemos incentivar a los clientes que se suscriban ofreciendo un cup\u00f3n de descuento en su siguiente compra, enviar informaci\u00f3n de productos que tengan afinidad con ese tipo de clientes, tambi\u00e9n podemos poner algunos enlaces que inviten al cliente a conocer las novedades de la tienda.<\/p>\n<p>Este tipo de herramientas pueden ayudar a mejorar la forma de atraer a los futuros clientes, recuerda que en Ando Haciendo Eso de la Web te ayudamos a optimizar estas herramientas para obtener mejores resultados en tu tienda virtual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El correo electr\u00f3nico se ha vuelto una herramienta fundamental y una pieza clave para poder utilizar diversas aplicaciones, hacer compras por internet, crear cuentas en redes sociales, requisito para tr\u00e1mites &#8230; <a title=\"Email Marketing\" class=\"read-more\" href=\"http:\/\/ando.mx\/enterate\/email-marketing\/\" aria-label=\"Leer m\u00e1s sobre Email Marketing\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":1518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enterate","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Email Marketing - ANDO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ando.mx\/enterate\/email-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Email Marketing - ANDO\" \/>\n<meta property=\"og:description\" content=\"El correo electr\u00f3nico se ha vuelto una herramienta fundamental y una pieza clave para poder utilizar diversas aplicaciones, hacer compras por internet, crear cuentas en redes sociales, requisito para tr\u00e1mites ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ando.mx\/enterate\/email-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"ANDO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/andohaciendo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-30T19:03:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T18:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Soporte ANDO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@andohaciendo\" \/>\n<meta name=\"twitter:site\" content=\"@andohaciendo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Soporte ANDO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/\"},\"author\":{\"name\":\"Soporte ANDO\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#\\\/schema\\\/person\\\/4fe7638197cabb10d7e782c1e5da1035\"},\"headline\":\"Email Marketing\",\"datePublished\":\"2022-01-30T19:03:05+00:00\",\"dateModified\":\"2022-11-29T18:19:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/\"},\"wordCount\":514,\"publisher\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ANDO-Blog-Email-Marketing.jpg\",\"articleSection\":[\"Ent\u00e9rate\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/\",\"url\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/\",\"name\":\"Email Marketing - ANDO\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ANDO-Blog-Email-Marketing.jpg\",\"datePublished\":\"2022-01-30T19:03:05+00:00\",\"dateModified\":\"2022-11-29T18:19:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#primaryimage\",\"url\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ANDO-Blog-Email-Marketing.jpg\",\"contentUrl\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ANDO-Blog-Email-Marketing.jpg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/email-marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Email Marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#website\",\"url\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/\",\"name\":\"ANDO\",\"description\":\"Nosotros somos ANDO HACIENDO ESO DE LA WEB, S.A. DE C.V. y somos una Agencia de Marketing y Publicidad Digital que comunica, dise\u00f1a, desarrolla, ense\u00f1a, promociona y administra \u201ctodo eso de la web\u201d desde el a\u00f1o 2006.\",\"publisher\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#organization\",\"name\":\"ANDO HACIENDO ESO DE LA WEB\",\"url\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ando_logo_ch.png\",\"contentUrl\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ando_logo_ch.png\",\"width\":400,\"height\":120,\"caption\":\"ANDO HACIENDO ESO DE LA WEB\"},\"image\":{\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/andohaciendo\\\/\",\"https:\\\/\\\/x.com\\\/andohaciendo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ando-haciendo-eso-de-la-web-s-a-de-c-v-\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/andoweb\",\"https:\\\/\\\/www.instagram.com\\\/andohaciendo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/ando.mx\\\/enterate\\\/#\\\/schema\\\/person\\\/4fe7638197cabb10d7e782c1e5da1035\",\"name\":\"Soporte ANDO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g\",\"caption\":\"Soporte ANDO\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Email Marketing - ANDO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ando.mx\/enterate\/email-marketing\/","og_locale":"es_MX","og_type":"article","og_title":"Email Marketing - ANDO","og_description":"El correo electr\u00f3nico se ha vuelto una herramienta fundamental y una pieza clave para poder utilizar diversas aplicaciones, hacer compras por internet, crear cuentas en redes sociales, requisito para tr\u00e1mites ... Leer m\u00e1s","og_url":"http:\/\/ando.mx\/enterate\/email-marketing\/","og_site_name":"ANDO","article_publisher":"https:\/\/www.facebook.com\/andohaciendo\/","article_published_time":"2022-01-30T19:03:05+00:00","article_modified_time":"2022-11-29T18:19:54+00:00","og_image":[{"width":1200,"height":600,"url":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg","type":"image\/jpeg"}],"author":"Soporte ANDO","twitter_card":"summary_large_image","twitter_creator":"@andohaciendo","twitter_site":"@andohaciendo","twitter_misc":{"Escrito por":"Soporte ANDO","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#article","isPartOf":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/"},"author":{"name":"Soporte ANDO","@id":"http:\/\/ando.mx\/enterate\/#\/schema\/person\/4fe7638197cabb10d7e782c1e5da1035"},"headline":"Email Marketing","datePublished":"2022-01-30T19:03:05+00:00","dateModified":"2022-11-29T18:19:54+00:00","mainEntityOfPage":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/"},"wordCount":514,"publisher":{"@id":"http:\/\/ando.mx\/enterate\/#organization"},"image":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#primaryimage"},"thumbnailUrl":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg","articleSection":["Ent\u00e9rate"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/ando.mx\/enterate\/email-marketing\/","url":"http:\/\/ando.mx\/enterate\/email-marketing\/","name":"Email Marketing - ANDO","isPartOf":{"@id":"http:\/\/ando.mx\/enterate\/#website"},"primaryImageOfPage":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#primaryimage"},"image":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#primaryimage"},"thumbnailUrl":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg","datePublished":"2022-01-30T19:03:05+00:00","dateModified":"2022-11-29T18:19:54+00:00","breadcrumb":{"@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ando.mx\/enterate\/email-marketing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#primaryimage","url":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg","contentUrl":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2022\/01\/ANDO-Blog-Email-Marketing.jpg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"http:\/\/ando.mx\/enterate\/email-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"http:\/\/ando.mx\/enterate\/"},{"@type":"ListItem","position":2,"name":"Email Marketing"}]},{"@type":"WebSite","@id":"http:\/\/ando.mx\/enterate\/#website","url":"http:\/\/ando.mx\/enterate\/","name":"ANDO","description":"Nosotros somos ANDO HACIENDO ESO DE LA WEB, S.A. DE C.V. y somos una Agencia de Marketing y Publicidad Digital que comunica, dise\u00f1a, desarrolla, ense\u00f1a, promociona y administra \u201ctodo eso de la web\u201d desde el a\u00f1o 2006.","publisher":{"@id":"http:\/\/ando.mx\/enterate\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ando.mx\/enterate\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/ando.mx\/enterate\/#organization","name":"ANDO HACIENDO ESO DE LA WEB","url":"http:\/\/ando.mx\/enterate\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ando.mx\/enterate\/#\/schema\/logo\/image\/","url":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2021\/10\/ando_logo_ch.png","contentUrl":"http:\/\/ando.mx\/enterate\/wp-content\/uploads\/2021\/10\/ando_logo_ch.png","width":400,"height":120,"caption":"ANDO HACIENDO ESO DE LA WEB"},"image":{"@id":"http:\/\/ando.mx\/enterate\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/andohaciendo\/","https:\/\/x.com\/andohaciendo","https:\/\/www.linkedin.com\/company\/ando-haciendo-eso-de-la-web-s-a-de-c-v-","https:\/\/www.youtube.com\/user\/andoweb","https:\/\/www.instagram.com\/andohaciendo\/"]},{"@type":"Person","@id":"http:\/\/ando.mx\/enterate\/#\/schema\/person\/4fe7638197cabb10d7e782c1e5da1035","name":"Soporte ANDO","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d6af12702ad328f21ced7a8678a26336fa7477fa74a512f5a3d36ade873f284?s=96&d=mm&r=g","caption":"Soporte ANDO"}}]}},"_links":{"self":[{"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/posts\/1477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/comments?post=1477"}],"version-history":[{"count":0,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/posts\/1477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/media\/1518"}],"wp:attachment":[{"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/media?parent=1477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/categories?post=1477"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ando.mx\/enterate\/wp-json\/wp\/v2\/tags?post=1477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}